{"id":724,"count":2,"description":"","link":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/","name":"Centrais Telef\u00f3nicas","slug":"centrais-telefonicas","taxonomy":"product_cat","parent":335,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cyberlogics Technologies Angola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/index.php\\\/product-category\\\/acessorios-2\\\/centrais-telefonicas\\\/\",\"url\":\"https:\\\/\\\/cyberlogics.ao\\\/index.php\\\/product-category\\\/acessorios-2\\\/centrais-telefonicas\\\/\",\"name\":\"Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/index.php\\\/product-category\\\/acessorios-2\\\/centrais-telefonicas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/index.php\\\/product-category\\\/acessorios-2\\\/centrais-telefonicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cyberlogics.ao\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acess\u00f3rios\",\"item\":\"https:\\\/\\\/cyberlogics.ao\\\/index.php\\\/product-category\\\/acessorios-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Centrais Telef\u00f3nicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#website\",\"url\":\"https:\\\/\\\/cyberlogics.ao\\\/\",\"name\":\"Cyberlogics Technologies Angola\",\"description\":\"Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyberlogics.ao\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#organization\",\"name\":\"Cyberlogics Ao Technologies - Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica\",\"url\":\"https:\\\/\\\/cyberlogics.ao\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyberlogics.ao\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CT-logo.png\",\"contentUrl\":\"https:\\\/\\\/cyberlogics.ao\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/CT-logo.png\",\"width\":190,\"height\":75,\"caption\":\"Cyberlogics Ao Technologies - Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica\"},\"image\":{\"@id\":\"https:\\\/\\\/cyberlogics.ao\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/","og_locale":"pt_PT","og_type":"article","og_title":"Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola","og_url":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/","og_site_name":"Cyberlogics Technologies Angola","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/","url":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/","name":"Arquivo de Centrais Telef\u00f3nicas - Cyberlogics Technologies Angola","isPartOf":{"@id":"https:\/\/cyberlogics.ao\/#website"},"breadcrumb":{"@id":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/centrais-telefonicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cyberlogics.ao\/"},{"@type":"ListItem","position":2,"name":"Acess\u00f3rios","item":"https:\/\/cyberlogics.ao\/index.php\/product-category\/acessorios-2\/"},{"@type":"ListItem","position":3,"name":"Centrais Telef\u00f3nicas"}]},{"@type":"WebSite","@id":"https:\/\/cyberlogics.ao\/#website","url":"https:\/\/cyberlogics.ao\/","name":"Cyberlogics Technologies Angola","description":"Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica","publisher":{"@id":"https:\/\/cyberlogics.ao\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyberlogics.ao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/cyberlogics.ao\/#organization","name":"Cyberlogics Ao Technologies - Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica","url":"https:\/\/cyberlogics.ao\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/cyberlogics.ao\/#\/schema\/logo\/image\/","url":"https:\/\/cyberlogics.ao\/wp-content\/uploads\/2022\/04\/CT-logo.png","contentUrl":"https:\/\/cyberlogics.ao\/wp-content\/uploads\/2022\/04\/CT-logo.png","width":190,"height":75,"caption":"Cyberlogics Ao Technologies - Loja Online de Licen\u00e7as de Softwares e Inform\u00e1tica"},"image":{"@id":"https:\/\/cyberlogics.ao\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cyberlogics.ao\/index.php\/wp-json\/wp\/v2\/product_cat\/724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyberlogics.ao\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cyberlogics.ao\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/cyberlogics.ao\/index.php\/wp-json\/wp\/v2\/product_cat\/335"}],"wp:post_type":[{"href":"https:\/\/cyberlogics.ao\/index.php\/wp-json\/wp\/v2\/product?product_cat=724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}